{"id":17128,"date":"2020-09-13T21:37:29","date_gmt":"2020-09-13T20:37:29","guid":{"rendered":"https:\/\/diariodeavisos.elespanol.com\/canariasenred\/?p=17128"},"modified":"2020-09-13T21:37:29","modified_gmt":"2020-09-13T20:37:29","slug":"mata-en-plena-calle-al-violador-de-su-hija","status":"publish","type":"post","link":"https:\/\/diariodeavisos.elespanol.com\/canariasenred\/mata-en-plena-calle-al-violador-de-su-hija\/","title":{"rendered":"Mata en plena calle al violador de su hija"},"content":{"rendered":"<p>Un hombre ha apu\u00f1alado y matado a un hombre que viol\u00f3 a su hija en Le\u00f3n, estado de Guanajuato (M\u00e9xico). Seg\u00fan publica &#8216;Radio F\u00f3rmula&#8217;, el padre estaba esperando al hombre que hab\u00eda abusado de su hija en la puerta de la Fiscal\u00eda de Le\u00f3n, adonde hab\u00eda ido a declarar.<\/p><div id=\"cer-728154253\" class=\"cer-contenido cer-entity-placement\" style=\"margin-top: 22px;margin-bottom: 22px;\"><div id=\"item_ATF_center_afterp1\"><\/div><\/div>\n<p>En unas im\u00e1genes captadas por una c\u00e1mara de seguridad se puede ver como el padre saca un cuchillo de su bolsillo y se acerca al presunto violador. En ese momento, le apu\u00f1al\u00f3 en el pecho haci\u00e9ndolo caer al suelo.<\/p><div id=\"cer-1293598686\" class=\"cer-contenido_2 cer-entity-placement\" style=\"margin-top: 22px;margin-bottom: 22px;\"><div id=\"intext_inread_video\"><\/div><\/div>\n<p>El hombre muri\u00f3 al d\u00eda siguiente en el hospital a causa de las heridas que le caus\u00f3 la herida. La Fiscal\u00eda General de Guanajuato ha confirmado a &#8216;Radio F\u00f3rmula&#8217; que el padre de la joven est\u00e1 detenido y se le imputa un cargo de homicidio.<\/p><div id=\"cer-1868320663\" class=\"cer-parrafo-3 cer-entity-placement\" style=\"margin-bottom: 42px;\"><!-- Desktop -->\r\n<div class=\"addoor-widget\" id=\"addoor-widget-1185\"><\/div>\r\n<!-- Mobile -->\r\n<div class=\"addoor-widget\" id=\"addoor-widget-2561\"><\/div><\/div>\n<p>El Juez de la causa dict\u00f3 prisi\u00f3n preventiva para el imputado, quien deber\u00e1 comparecer de nueva cuenta ante el Juzgado de Oralidad Penal para ser sentenciado por el delito.<\/p><div id=\"cer-2736195876\" class=\"cer-parrafo-3-2 cer-entity-placement\" style=\"margin-bottom: 22px;\"><script>(function(d,s,n){var js,fjs=d.getElementsByTagName(s)[0];js=d.createElement(s);js.className=n;js.src=\"\/\/player.ex.co\/player\/80da6adf-177e-4ffe-9e60-9d2535571cce\";fjs.parentNode.insertBefore(js,fjs);}(document,\"script\",\"exco-player\"));<\/script><div id=\"80da6adf-177e-4ffe-9e60-9d2535571cce\"><\/div><\/div>\n<div id=\"cer-1584606642\" class=\"cer-despues-del-contenido cer-entity-placement\" style=\"margin-top: 22px;margin-bottom: 22px;\"><div class=\"addoor-widget\" id=\"addoor-widget-1184\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Un hombre ha apu\u00f1alado y matado a un hombre que viol\u00f3 a su hija en Le\u00f3n, estado de Guanajuato (M\u00e9xico). Seg\u00fan publica &#8216;Radio F\u00f3rmula&#8217;, el padre estaba esperando al hombre que hab\u00eda abusado de su hija en la puerta de la Fiscal\u00eda de Le\u00f3n, adonde hab\u00eda ido a declarar. En unas im\u00e1genes captadas por una [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":17129,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[139],"tags":[817,348,3093],"class_list":{"0":"post-17128","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-internacional","8":"tag-hija","9":"tag-mata","10":"tag-violador"},"_links":{"self":[{"href":"https:\/\/diariodeavisos.elespanol.com\/canariasenred\/wp-json\/wp\/v2\/posts\/17128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodeavisos.elespanol.com\/canariasenred\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodeavisos.elespanol.com\/canariasenred\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodeavisos.elespanol.com\/canariasenred\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodeavisos.elespanol.com\/canariasenred\/wp-json\/wp\/v2\/comments?post=17128"}],"version-history":[{"count":0,"href":"https:\/\/diariodeavisos.elespanol.com\/canariasenred\/wp-json\/wp\/v2\/posts\/17128\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodeavisos.elespanol.com\/canariasenred\/wp-json\/wp\/v2\/media\/17129"}],"wp:attachment":[{"href":"https:\/\/diariodeavisos.elespanol.com\/canariasenred\/wp-json\/wp\/v2\/media?parent=17128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodeavisos.elespanol.com\/canariasenred\/wp-json\/wp\/v2\/categories?post=17128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodeavisos.elespanol.com\/canariasenred\/wp-json\/wp\/v2\/tags?post=17128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}